{"id":1271,"date":"2026-08-16T16:16:09","date_gmt":"2026-08-16T14:16:09","guid":{"rendered":"https:\/\/leadthemood.com\/mataro\/botiga-online\/"},"modified":"2026-08-16T17:24:59","modified_gmt":"2026-08-16T15:24:59","slug":"botiga-online","status":"publish","type":"page","link":"https:\/\/leadthemood.com\/ca\/mataro\/botiga-online\/","title":{"rendered":"Botigues Online a Matar\u00f3"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":0,"parent":1158,"menu_order":142,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1271","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ag\u00e8ncia ecommerce a Matar\u00f3 | Lead The Mood<\/title>\n<meta name=\"description\" content=\"Botigues online a Matar\u00f3: cat\u00e0leg, estoc, pagaments i enviaments com un sol sistema, sense perdre el que ja funciona a la venda f\u00edsica. Des de 8.500 \u20ac.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/leadthemood.com\/ca\/mataro\/botiga-online\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ag\u00e8ncia ecommerce a Matar\u00f3 | Lead The Mood\" \/>\n<meta property=\"og:description\" content=\"Botigues online a Matar\u00f3: cat\u00e0leg, estoc, pagaments i enviaments com un sol sistema, sense perdre el que ja funciona a la venda f\u00edsica. Des de 8.500 \u20ac.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/leadthemood.com\/ca\/mataro\/botiga-online\/\" \/>\n<meta property=\"og:site_name\" content=\"Lead The Mood\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-16T15:24:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/leadthemood.com\/wp-content\/uploads\/2026\/08\/mood-terraza-selfie.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/leadthemood.com\\\/ca\\\/mataro\\\/botiga-online\\\/\",\"url\":\"https:\\\/\\\/leadthemood.com\\\/ca\\\/mataro\\\/botiga-online\\\/\",\"name\":\"Ag\u00e8ncia ecommerce a Matar\u00f3 | Lead The Mood\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leadthemood.com\\\/ca\\\/#website\"},\"datePublished\":\"2026-08-16T14:16:09+00:00\",\"dateModified\":\"2026-08-16T15:24:59+00:00\",\"description\":\"Botigues online a Matar\u00f3: cat\u00e0leg, estoc, pagaments i enviaments com un sol sistema, sense perdre el que ja funciona a la venda f\u00edsica. Des de 8.500 \u20ac.\",\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/leadthemood.com\\\/ca\\\/mataro\\\/botiga-online\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/leadthemood.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/leadthemood.com\\\/ca\\\/\",\"name\":\"Lead The Mood\",\"description\":\"Agencia de marketing digital en Matar\u00f3 y el Maresme\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/leadthemood.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ag\u00e8ncia ecommerce a Matar\u00f3 | Lead The Mood","description":"Botigues online a Matar\u00f3: cat\u00e0leg, estoc, pagaments i enviaments com un sol sistema, sense perdre el que ja funciona a la venda f\u00edsica. Des de 8.500 \u20ac.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/leadthemood.com\/ca\/mataro\/botiga-online\/","og_locale":"ca_ES","og_type":"article","og_title":"Ag\u00e8ncia ecommerce a Matar\u00f3 | Lead The Mood","og_description":"Botigues online a Matar\u00f3: cat\u00e0leg, estoc, pagaments i enviaments com un sol sistema, sense perdre el que ja funciona a la venda f\u00edsica. Des de 8.500 \u20ac.","og_url":"https:\/\/leadthemood.com\/ca\/mataro\/botiga-online\/","og_site_name":"Lead The Mood","article_modified_time":"2026-08-16T15:24:59+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/leadthemood.com\/wp-content\/uploads\/2026\/08\/mood-terraza-selfie.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/leadthemood.com\/ca\/mataro\/botiga-online\/","url":"https:\/\/leadthemood.com\/ca\/mataro\/botiga-online\/","name":"Ag\u00e8ncia ecommerce a Matar\u00f3 | Lead The Mood","isPartOf":{"@id":"https:\/\/leadthemood.com\/ca\/#website"},"datePublished":"2026-08-16T14:16:09+00:00","dateModified":"2026-08-16T15:24:59+00:00","description":"Botigues online a Matar\u00f3: cat\u00e0leg, estoc, pagaments i enviaments com un sol sistema, sense perdre el que ja funciona a la venda f\u00edsica. Des de 8.500 \u20ac.","inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/leadthemood.com\/ca\/mataro\/botiga-online\/"]}]},{"@type":"WebSite","@id":"https:\/\/leadthemood.com\/ca\/#website","url":"https:\/\/leadthemood.com\/ca\/","name":"Lead The Mood","description":"Agencia de marketing digital en Matar\u00f3 y el Maresme","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/leadthemood.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"}]}},"_links":{"self":[{"href":"https:\/\/leadthemood.com\/ca\/wp-json\/wp\/v2\/pages\/1271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leadthemood.com\/ca\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/leadthemood.com\/ca\/wp-json\/wp\/v2\/types\/page"}],"replies":[{"embeddable":true,"href":"https:\/\/leadthemood.com\/ca\/wp-json\/wp\/v2\/comments?post=1271"}],"version-history":[{"count":0,"href":"https:\/\/leadthemood.com\/ca\/wp-json\/wp\/v2\/pages\/1271\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/leadthemood.com\/ca\/wp-json\/wp\/v2\/pages\/1158"}],"wp:attachment":[{"href":"https:\/\/leadthemood.com\/ca\/wp-json\/wp\/v2\/media?parent=1271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}